{"id":58129,"date":"2022-06-29T07:52:07","date_gmt":"2022-06-29T06:52:07","guid":{"rendered":"https:\/\/noniussolutions.com\/?p=58129"},"modified":"2025-12-22T19:00:06","modified_gmt":"2025-12-22T19:00:06","slug":"a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada","status":"publish","type":"post","link":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/","title":{"rendered":"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;3%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;54866&#8243; background_image_position=&#8221;center bottom&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;3px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; mobile_disable_entrance_animation=&#8221;true&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;very_subtle&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;600&#8243;][image_with_animation image_url=&#8221;52089&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;3%&#8221; bottom_padding_phone=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1656496432735{padding-top: 20px !important;padding-bottom: 10px !important;}&#8221;]\n<h5><span style=\"color: #1e83ec;\"><b>Seja por RF (cabo coaxial), Full IP ou h\u00edbrido, voc\u00ea pode contar conosco para fornecer a solu\u00e7\u00e3o certa com novas interfaces, temas e uma experi\u00eancia de usu\u00e1rio refinada para poder atender a qualquer padr\u00e3o de marca.<\/b><\/span><\/h5>\n<p>&nbsp;<\/p>\n<p>A <a href=\"https:\/\/noniussolutions.com\/hotel-tv\/\" target=\"_blank\" rel=\"noopener\">solu\u00e7\u00e3o de TV Interativa da Nonius<\/a> est\u00e1 implantada em mais de 980 propriedades em todo o mundo. <b>Totalmente personaliz\u00e1vel<\/b> aos padr\u00f5es de marca do seu hotel e<b> compat\u00edvel com qualquer TV<\/b>, oferecemos quatro diferentes tipos de modelos vers\u00e1teis com uma <b>interface de alta defini\u00e7\u00e3o<\/b>, assim como <b>servi\u00e7os de cria\u00e7\u00e3o de conte\u00fado <\/b>para garantir uma experi\u00eancia envolvente.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; bottom_margin=&#8221;1%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;fontawesome&#8221; el_class=&#8221;popmake-48019&#8243; text=&#8221;Saiba mais&#8221; css_animation=&#8221;zoomIn&#8221; icon_fontawesome=&#8221;fa fa-envelope-o&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;3%&#8221; bottom_padding_phone=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-2%&#8221; bottom_margin=&#8221;-1%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#1e83ec&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]<span style=\"font-weight: 400;\">Confira o v\u00eddeo para saber mais sobre nossos novos modelos de interface:<\/span>[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_video link=&#8221;https:\/\/youtu.be\/6kC3zn0Dpxg?feature=shared&#8221; css=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;6%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; size=&#8221;medium&#8221; open_new_tab=&#8221;&#8221; button_style=&#8221;regular&#8221; button_color=&#8221;Accent-Color&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;&#8221; solid_text_color_override=&#8221;&#8221; hover_color_override=&#8221;&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;fontawesome&#8221; nofollow=&#8221;&#8221; el_class=&#8221;popmake-27598&#8243; button_id=&#8221;&#8221; url=&#8221;#&#8221; text=&#8221;More Info&#8221; css_animation=&#8221;zoomIn&#8221; icon_fontawesome=&#8221;fa fa-envelope-o&#8221; margin_top=&#8221;&#8221; margin_bottom=&#8221;&#8221; margin_left=&#8221;&#8221; margin_right=&#8221;&#8221; icon_iconsmind=&#8221;&#8221; icon_linecons=&#8221;&#8221; icon_steadysets=&#8221;&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-3%&#8221; bottom_margin=&#8221;1%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]A TV Interativa \u00e9 a solu\u00e7\u00e3o perfeita para que os hot\u00e9is ofere\u00e7am <b>entretenimento de alta qualidade<\/b>, incluindo streaming de conte\u00fado do h\u00f3spede diretamente na TV do quarto atrav\u00e9s do <a href=\"https:\/\/noniussolutions.com\/chromecast-hotel\/\" target=\"_blank\" rel=\"noopener\">Nonius Cast<\/a> (Netflix, YouTube, Bluetooth, Spotify e outros).<span style=\"font-weight: 400;\">. Al\u00e9m de informar os h\u00f3spedes sobre os servi\u00e7os do hotel e as atra\u00e7\u00f5es da cidade, esta plataforma totalmente integrada permite que as propriedades aumentem a receita dos pedidos de servi\u00e7os de quarto conectando o portal de TV com o PMS, PDV, e-mail e impressoras da cozinha.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#1e83ec&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;2%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#1e83ec&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Informe, impressione e aumente a receita com a nossa plataforma de TV e reduza os custos de pessoal via digitaliza\u00e7\u00e3o.&#8221; font_container=&#8221;tag:h5|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; bottom_padding_phone=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; size=&#8221;medium&#8221; open_new_tab=&#8221;&#8221; button_style=&#8221;regular&#8221; button_color=&#8221;Accent-Color&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;&#8221; solid_text_color_override=&#8221;&#8221; hover_color_override=&#8221;&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;fontawesome&#8221; nofollow=&#8221;&#8221; el_class=&#8221;popmake-27598&#8243; button_id=&#8221;&#8221; url=&#8221;#&#8221; text=&#8221;More Info&#8221; css_animation=&#8221;zoomIn&#8221; icon_fontawesome=&#8221;fa fa-envelope-o&#8221; margin_top=&#8221;&#8221; margin_bottom=&#8221;&#8221; margin_left=&#8221;&#8221; margin_right=&#8221;&#8221; icon_iconsmind=&#8221;&#8221; icon_linecons=&#8221;&#8221; icon_steadysets=&#8221;&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;1%&#8221; bottom_margin=&#8221;1%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<p class=\"p1\"><span style=\"font-weight: 400;\">Seja baseado na nuvem ou no local, a solu\u00e7\u00e3o de TV Interativa Nonius \u00e9 escal\u00e1vel, adequando-se a qualquer tipo ou tamanho de propriedade. O hotel tamb\u00e9m tem a op\u00e7\u00e3o de escolher entre oferecer filmes gratuitos ou de receita compartilhada, outra forma de aumentar o faturamento com uma interface de \u00faltima gera\u00e7\u00e3o centrada no usu\u00e1rio.  <\/span><\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;1%&#8221; bottom_margin_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;fontawesome&#8221; el_class=&#8221;popmake-48019&#8243; text=&#8221;Agendar uma demo&#8221; css_animation=&#8221;zoomIn&#8221; icon_fontawesome=&#8221;fa fa-envelope-o&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;5%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; right_margin=&#8221;0,5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;52068&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/noniussolutions.com\/2022\/06\/09\/the-one-hundred-shoreditch-trusts-nonius-solutions-to-deliver-a-fully-digital-experience-in-their-cool-east-london-hotel\/&#8221;][vc_column_text]\n<p class=\"entry-title\"><a href=\"https:\/\/noniussolutions.com\/2022\/06\/09\/the-one-hundred-shoreditch-trusts-nonius-solutions-to-deliver-a-fully-digital-experience-in-their-cool-east-london-hotel\/\" target=\"_blank\" rel=\"noopener\">O One Hundred Shoreditch confia nas solu\u00e7\u00f5es da Nonius para proporcionar uma experi\u00eancia totalmente digital no seu incr\u00edvel hotel no leste de Londres<\/a><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin=&#8221;0,5%&#8221; constrain_group_2=&#8221;yes&#8221; right_margin=&#8221;0,5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;51237&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/noniussolutions.com\/2021\/09\/08\/hard-rock-has-chosen-nonius-as-their-preferred-partner-for-tv-and-cast-solutions\/&#8221;][vc_column_text]\n<p class=\"entry-title\"><a href=\"https:\/\/noniussolutions.com\/2021\/09\/08\/hard-rock-has-chosen-nonius-as-their-preferred-partner-for-tv-and-cast-solutions\/\" target=\"_blank\" rel=\"noopener\">O Hard Rock escolheu a Nonius como a sua fornecedora preferencial das solu\u00e7\u00f5es de TV e Cast<\/a><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin=&#8221;0,5%&#8221; constrain_group_2=&#8221;yes&#8221; right_margin=&#8221;0,5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;51285&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/noniussolutions.com\/2021\/10\/07\/la-colombe-dor-hotel-invests-in-state-of-the-art-guest-technology\/&#8221;][vc_column_text]\n<p class=\"entry-title\"><a href=\"https:\/\/noniussolutions.com\/2021\/10\/07\/la-colombe-dor-hotel-invests-in-state-of-the-art-guest-technology\/\" target=\"_blank\" rel=\"noopener\">La Colombe D\u2019Or Hotel investe em tecnologia de ponta para os h\u00f3spedes<\/a><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin=&#8221;0,5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;51314&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/noniussolutions.com\/2021\/11\/11\/tivoli-mofarrej-sao-paulo-hotel-reinforces-its-trust-in-nonius-technology\/&#8221;][vc_column_text]\n<p class=\"entry-title\"><a href=\"https:\/\/noniussolutions.com\/2021\/11\/11\/tivoli-mofarrej-sao-paulo-hotel-reinforces-its-trust-in-nonius-technology\/\" target=\"_blank\" rel=\"noopener\">Tivoli Mofarrej S\u00e3o Paulo Hotel refor\u00e7a confian\u00e7a nas tecnologias Nonius<\/a><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;13%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_single_testimonial testimonial_style=&#8221;basic_left_image&#8221; image=&#8221;79593&#8243; name=&#8221;Pedro Agostinho da Silva&#8221; subtitle=&#8221;TV Product Unit Director at Nonius&#8221; quote=&#8221;It&apos;s never been so easy for hotels to engage with guests before. Nonius Interactive TV portals are specifically designed to deliver the best usability while promoting the hotel brand design.&lt;br&gt;\u201cNunca foi t\u00e3o f\u00e1cil para os hot\u00e9is interagirem com os h\u00f3spedes. Os portais da TV Interativa da Nonius s\u00e3o projetados especificamente para oferecer a melhor usabilidade enquanto promovem o design da marca do hotel. Estes excelentes layouts levam os h\u00f3spedes a navegar por incr\u00edveis aplicativos informativos que tamb\u00e9m reduzem os custos das opera\u00e7\u00f5es e do material publicit\u00e1rio do hotel. Al\u00e9m disso, nossa equipe de cria\u00e7\u00e3o de conte\u00fado est\u00e1 totalmente dispon\u00edvel para colaborar e oferecer m\u00eddia de alta qualidade, promovendo a usabilidade e tirando o melhor proveito da grande qualidade das TVs atuais.  &#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;3%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":52094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[160,161,156],"tags":[],"class_list":{"0":"post-58129","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"category-produto","9":"category-tv-interativa"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada &#8211; Nonius<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada &#8211; Nonius\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;3%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/\" \/>\n<meta property=\"og:site_name\" content=\"Nonius\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noniussoftware\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T06:52:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T19:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noniussolutions.com\/wp-content\/uploads\/2022\/06\/News_Header_The-most-versatile-Interactive-TV.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1087\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"margarida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"margarida\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/\"},\"author\":{\"name\":\"margarida\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/380040564e6e330266c6db64ed3ade42\"},\"headline\":\"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada\",\"datePublished\":\"2022-06-29T06:52:07+00:00\",\"dateModified\":\"2025-12-22T19:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/\"},\"wordCount\":3122,\"publisher\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noniussolutions.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/News_Header_The-most-versatile-Interactive-TV.webp\",\"articleSection\":[\"Not\u00edcias\",\"Produto\",\"TV Interativa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/\",\"url\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/\",\"name\":\"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada &#8211; Nonius\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noniussolutions.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/News_Header_The-most-versatile-Interactive-TV.webp\",\"datePublished\":\"2022-06-29T06:52:07+00:00\",\"dateModified\":\"2025-12-22T19:00:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noniussolutions.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/News_Header_The-most-versatile-Interactive-TV.webp\",\"contentUrl\":\"https:\\\/\\\/noniussolutions.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/News_Header_The-most-versatile-Interactive-TV.webp\",\"width\":1920,\"height\":1087},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/2022\\\/06\\\/29\\\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/\",\"name\":\"Nonius\",\"description\":\"Hospitality Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#organization\",\"name\":\"Nonius\",\"url\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noniussolutions.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-N.png\",\"contentUrl\":\"https:\\\/\\\/noniussolutions.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-N.png\",\"width\":500,\"height\":500,\"caption\":\"Nonius\"},\"image\":{\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noniussoftware\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nonius\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NoniusSoft\",\"https:\\\/\\\/www.instagram.com\\\/noniussolutions\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noniussolutions.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/380040564e6e330266c6db64ed3ade42\",\"name\":\"margarida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c3bae4db994890b43a9210fd1c4a1fc0a52b1cc4f5d9180ec4457f55e887a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c3bae4db994890b43a9210fd1c4a1fc0a52b1cc4f5d9180ec4457f55e887a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c3bae4db994890b43a9210fd1c4a1fc0a52b1cc4f5d9180ec4457f55e887a33?s=96&d=mm&r=g\",\"caption\":\"margarida\"},\"sameAs\":[\"https:\\\/\\\/noniussolutions.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada &#8211; Nonius","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/","og_locale":"pt_BR","og_type":"article","og_title":"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada &#8211; Nonius","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;3%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/","og_site_name":"Nonius","article_publisher":"https:\/\/www.facebook.com\/noniussoftware\/","article_published_time":"2022-06-29T06:52:07+00:00","article_modified_time":"2025-12-22T19:00:06+00:00","og_image":[{"width":1920,"height":1087,"url":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2022\/06\/News_Header_The-most-versatile-Interactive-TV.webp","type":"image\/webp"}],"author":"margarida","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"margarida","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#article","isPartOf":{"@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/"},"author":{"name":"margarida","@id":"https:\/\/noniussolutions.com\/pt-br\/#\/schema\/person\/380040564e6e330266c6db64ed3ade42"},"headline":"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada","datePublished":"2022-06-29T06:52:07+00:00","dateModified":"2025-12-22T19:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/"},"wordCount":3122,"publisher":{"@id":"https:\/\/noniussolutions.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#primaryimage"},"thumbnailUrl":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2022\/06\/News_Header_The-most-versatile-Interactive-TV.webp","articleSection":["Not\u00edcias","Produto","TV Interativa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/","url":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/","name":"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada &#8211; Nonius","isPartOf":{"@id":"https:\/\/noniussolutions.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#primaryimage"},"image":{"@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#primaryimage"},"thumbnailUrl":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2022\/06\/News_Header_The-most-versatile-Interactive-TV.webp","datePublished":"2022-06-29T06:52:07+00:00","dateModified":"2025-12-22T19:00:06+00:00","breadcrumb":{"@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#primaryimage","url":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2022\/06\/News_Header_The-most-versatile-Interactive-TV.webp","contentUrl":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2022\/06\/News_Header_The-most-versatile-Interactive-TV.webp","width":1920,"height":1087},{"@type":"BreadcrumbList","@id":"https:\/\/noniussolutions.com\/pt-br\/2022\/06\/29\/a-mais-versatil-solucao-de-tv-interativa-acaba-de-ser-reformulada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noniussolutions.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"A mais vers\u00e1til solu\u00e7\u00e3o de TV Interativa acaba de ser reformulada"}]},{"@type":"WebSite","@id":"https:\/\/noniussolutions.com\/pt-br\/#website","url":"https:\/\/noniussolutions.com\/pt-br\/","name":"Nonius","description":"Hospitality Technology","publisher":{"@id":"https:\/\/noniussolutions.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noniussolutions.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/noniussolutions.com\/pt-br\/#organization","name":"Nonius","url":"https:\/\/noniussolutions.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/noniussolutions.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2025\/11\/logo-N.png","contentUrl":"https:\/\/noniussolutions.com\/wp-content\/uploads\/2025\/11\/logo-N.png","width":500,"height":500,"caption":"Nonius"},"image":{"@id":"https:\/\/noniussolutions.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noniussoftware\/","https:\/\/www.linkedin.com\/company\/nonius\/","https:\/\/www.youtube.com\/user\/NoniusSoft","https:\/\/www.instagram.com\/noniussolutions\/"]},{"@type":"Person","@id":"https:\/\/noniussolutions.com\/pt-br\/#\/schema\/person\/380040564e6e330266c6db64ed3ade42","name":"margarida","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2c3bae4db994890b43a9210fd1c4a1fc0a52b1cc4f5d9180ec4457f55e887a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c3bae4db994890b43a9210fd1c4a1fc0a52b1cc4f5d9180ec4457f55e887a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c3bae4db994890b43a9210fd1c4a1fc0a52b1cc4f5d9180ec4457f55e887a33?s=96&d=mm&r=g","caption":"margarida"},"sameAs":["https:\/\/noniussolutions.com"]}]}},"_links":{"self":[{"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/posts\/58129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/comments?post=58129"}],"version-history":[{"count":0,"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/posts\/58129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/media\/52094"}],"wp:attachment":[{"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/media?parent=58129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/categories?post=58129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noniussolutions.com\/pt-br\/wp-json\/wp\/v2\/tags?post=58129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}